{"id":27375,"date":"2017-07-11T10:06:01","date_gmt":"2017-07-11T09:06:01","guid":{"rendered":"http:\/\/eva-vautier.com\/?p=27375"},"modified":"2020-09-03T08:53:24","modified_gmt":"2020-09-03T09:53:24","slug":"cote-la-revue-dazur-juillet-2017","status":"publish","type":"post","link":"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/","title":{"rendered":"C\u00f4te La revue d&#8217;azur juillet 2017"},"content":{"rendered":"<p><a href=\"http:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-27376\" src=\"http:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27.png\" alt=\"\" width=\"1200\" height=\"739\" srcset=\"https:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27.png 1200w, https:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27-800x493.png 800w, https:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27-64x39.png 64w, https:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27-300x185.png 300w, https:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27-1024x631.png 1024w, https:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27-768x473.png 768w, https:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27-237x146.png 237w, https:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27-50x31.png 50w, https:\/\/eva-vautier.com\/wp-content\/uploads\/2017\/07\/Capture-d\u2019\u00e9cran-2017-07-10-\u00e0-18.48.27-122x75.png 122w\" sizes=\"auto, (max-width:767px) 480px, (max-width:1200px) 100vw, 1200px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":135,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-27375","post","type-post","status-publish","format-standard","hentry","category-revue-de-presse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f4te La revue d&#039;azur juillet 2017 ~ Galerie Eva Vautier<\/title>\n<meta name=\"description\" content=\"Dans un bel espace d\u00e9di\u00e9 \u00e0 l\u2019art au c\u0153ur du quartier Lib\u00e9ration, Eva Vautier, offre un nouveau regard sur l\u2019art contemporain et ses pratiques artistiques (sculpture, photographie, peinture, dessin, vid\u00e9o). La galerie accueille de jeunes artistes \u00e9mergents comme des artistes issus de courants artistiques majeurs. Des performances et des d\u00e9bats rythment r\u00e9guli\u00e8rement les grandes expositions de l\u2019ann\u00e9e. La galerie propose \u00e9galement une s\u00e9lection de s\u00e9rigraphies et d\u2019\u00e9ditions limit\u00e9es en lien avec son actualit\u00e9 artistique et culturelle. Et pour les passionn\u00e9s l\u2019arthoth\u00e8que de la galerie offre un large choix des s\u00e9rigraphies \u00e0 la location. % % %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f4te La revue d&#039;azur juillet 2017 ~ Galerie Eva Vautier\" \/>\n<meta property=\"og:description\" content=\"Dans un bel espace d\u00e9di\u00e9 \u00e0 l\u2019art au c\u0153ur du quartier Lib\u00e9ration, Eva Vautier, offre un nouveau regard sur l\u2019art contemporain et ses pratiques artistiques (sculpture, photographie, peinture, dessin, vid\u00e9o). La galerie accueille de jeunes artistes \u00e9mergents comme des artistes issus de courants artistiques majeurs. Des performances et des d\u00e9bats rythment r\u00e9guli\u00e8rement les grandes expositions de l\u2019ann\u00e9e. La galerie propose \u00e9galement une s\u00e9lection de s\u00e9rigraphies et d\u2019\u00e9ditions limit\u00e9es en lien avec son actualit\u00e9 artistique et culturelle. Et pour les passionn\u00e9s l\u2019arthoth\u00e8que de la galerie offre un large choix des s\u00e9rigraphies \u00e0 la location. % % %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Galerie Eva Vautier\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/evavautier\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-11T09:06:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-03T09:53:24+00:00\" \/>\n<meta name=\"author\" content=\"eva Vautier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EvaVautier\" \/>\n<meta name=\"twitter:site\" content=\"@EvaVautier\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eva Vautier\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/cote-la-revue-dazur-juillet-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/cote-la-revue-dazur-juillet-2017\\\/\"},\"author\":{\"name\":\"eva Vautier\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#\\\/schema\\\/person\\\/84de9580a67b26ee729034fb0254ead4\"},\"headline\":\"C\u00f4te La revue d&#8217;azur juillet 2017\",\"datePublished\":\"2017-07-11T09:06:01+00:00\",\"dateModified\":\"2020-09-03T09:53:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/cote-la-revue-dazur-juillet-2017\\\/\"},\"wordCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#organization\"},\"articleSection\":[\"Revue de presse\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/cote-la-revue-dazur-juillet-2017\\\/\",\"url\":\"https:\\\/\\\/eva-vautier.com\\\/cote-la-revue-dazur-juillet-2017\\\/\",\"name\":\"C\u00f4te La revue d'azur juillet 2017 ~ Galerie Eva Vautier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#website\"},\"datePublished\":\"2017-07-11T09:06:01+00:00\",\"dateModified\":\"2020-09-03T09:53:24+00:00\",\"description\":\"Dans un bel espace d\u00e9di\u00e9 \u00e0 l\u2019art au c\u0153ur du quartier Lib\u00e9ration, Eva Vautier, offre un nouveau regard sur l\u2019art contemporain et ses pratiques artistiques (sculpture, photographie, peinture, dessin, vid\u00e9o). La galerie accueille de jeunes artistes \u00e9mergents comme des artistes issus de courants artistiques majeurs. Des performances et des d\u00e9bats rythment r\u00e9guli\u00e8rement les grandes expositions de l\u2019ann\u00e9e. La galerie propose \u00e9galement une s\u00e9lection de s\u00e9rigraphies et d\u2019\u00e9ditions limit\u00e9es en lien avec son actualit\u00e9 artistique et culturelle. Et pour les passionn\u00e9s l\u2019arthoth\u00e8que de la galerie offre un large choix des s\u00e9rigraphies \u00e0 la location. % % %\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eva-vautier.com\\\/cote-la-revue-dazur-juillet-2017\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/\",\"name\":\"Galerie Eva Vautier\",\"description\":\"Galerie d&#039;art contemporain\",\"publisher\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#organization\",\"name\":\"Galerie Eva Vautier\",\"url\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/eva-vautier.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/logo-galerie-illustrator-04-1.png\",\"contentUrl\":\"http:\\\/\\\/eva-vautier.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/logo-galerie-illustrator-04-1.png\",\"width\":200,\"height\":24,\"caption\":\"Galerie Eva Vautier\"},\"image\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/evavautier\\\/\",\"https:\\\/\\\/x.com\\\/EvaVautier\",\"https:\\\/\\\/www.instagram.com\\\/galerieevavautier\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#\\\/schema\\\/person\\\/84de9580a67b26ee729034fb0254ead4\",\"name\":\"eva Vautier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/wp-content\\\/litespeed\\\/avatar\\\/dd984889775f6320e22f927e54fb9523.jpg?ver=1788357180\",\"url\":\"https:\\\/\\\/eva-vautier.com\\\/wp-content\\\/litespeed\\\/avatar\\\/dd984889775f6320e22f927e54fb9523.jpg?ver=1788357180\",\"contentUrl\":\"https:\\\/\\\/eva-vautier.com\\\/wp-content\\\/litespeed\\\/avatar\\\/dd984889775f6320e22f927e54fb9523.jpg?ver=1788357180\",\"caption\":\"eva Vautier\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f4te La revue d'azur juillet 2017 ~ Galerie Eva Vautier","description":"Dans un bel espace d\u00e9di\u00e9 \u00e0 l\u2019art au c\u0153ur du quartier Lib\u00e9ration, Eva Vautier, offre un nouveau regard sur l\u2019art contemporain et ses pratiques artistiques (sculpture, photographie, peinture, dessin, vid\u00e9o). La galerie accueille de jeunes artistes \u00e9mergents comme des artistes issus de courants artistiques majeurs. Des performances et des d\u00e9bats rythment r\u00e9guli\u00e8rement les grandes expositions de l\u2019ann\u00e9e. La galerie propose \u00e9galement une s\u00e9lection de s\u00e9rigraphies et d\u2019\u00e9ditions limit\u00e9es en lien avec son actualit\u00e9 artistique et culturelle. Et pour les passionn\u00e9s l\u2019arthoth\u00e8que de la galerie offre un large choix des s\u00e9rigraphies \u00e0 la location. % % %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/","og_locale":"en_US","og_type":"article","og_title":"C\u00f4te La revue d'azur juillet 2017 ~ Galerie Eva Vautier","og_description":"Dans un bel espace d\u00e9di\u00e9 \u00e0 l\u2019art au c\u0153ur du quartier Lib\u00e9ration, Eva Vautier, offre un nouveau regard sur l\u2019art contemporain et ses pratiques artistiques (sculpture, photographie, peinture, dessin, vid\u00e9o). La galerie accueille de jeunes artistes \u00e9mergents comme des artistes issus de courants artistiques majeurs. Des performances et des d\u00e9bats rythment r\u00e9guli\u00e8rement les grandes expositions de l\u2019ann\u00e9e. La galerie propose \u00e9galement une s\u00e9lection de s\u00e9rigraphies et d\u2019\u00e9ditions limit\u00e9es en lien avec son actualit\u00e9 artistique et culturelle. Et pour les passionn\u00e9s l\u2019arthoth\u00e8que de la galerie offre un large choix des s\u00e9rigraphies \u00e0 la location. % % %","og_url":"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/","og_site_name":"Galerie Eva Vautier","article_publisher":"https:\/\/www.facebook.com\/evavautier\/","article_published_time":"2017-07-11T09:06:01+00:00","article_modified_time":"2020-09-03T09:53:24+00:00","author":"eva Vautier","twitter_card":"summary_large_image","twitter_creator":"@EvaVautier","twitter_site":"@EvaVautier","twitter_misc":{"Written by":"eva Vautier"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/#article","isPartOf":{"@id":"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/"},"author":{"name":"eva Vautier","@id":"https:\/\/eva-vautier.com\/en\/#\/schema\/person\/84de9580a67b26ee729034fb0254ead4"},"headline":"C\u00f4te La revue d&#8217;azur juillet 2017","datePublished":"2017-07-11T09:06:01+00:00","dateModified":"2020-09-03T09:53:24+00:00","mainEntityOfPage":{"@id":"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/"},"wordCount":7,"publisher":{"@id":"https:\/\/eva-vautier.com\/en\/#organization"},"articleSection":["Revue de presse"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/","url":"https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/","name":"C\u00f4te La revue d'azur juillet 2017 ~ Galerie Eva Vautier","isPartOf":{"@id":"https:\/\/eva-vautier.com\/en\/#website"},"datePublished":"2017-07-11T09:06:01+00:00","dateModified":"2020-09-03T09:53:24+00:00","description":"Dans un bel espace d\u00e9di\u00e9 \u00e0 l\u2019art au c\u0153ur du quartier Lib\u00e9ration, Eva Vautier, offre un nouveau regard sur l\u2019art contemporain et ses pratiques artistiques (sculpture, photographie, peinture, dessin, vid\u00e9o). La galerie accueille de jeunes artistes \u00e9mergents comme des artistes issus de courants artistiques majeurs. Des performances et des d\u00e9bats rythment r\u00e9guli\u00e8rement les grandes expositions de l\u2019ann\u00e9e. La galerie propose \u00e9galement une s\u00e9lection de s\u00e9rigraphies et d\u2019\u00e9ditions limit\u00e9es en lien avec son actualit\u00e9 artistique et culturelle. Et pour les passionn\u00e9s l\u2019arthoth\u00e8que de la galerie offre un large choix des s\u00e9rigraphies \u00e0 la location. % % %","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eva-vautier.com\/cote-la-revue-dazur-juillet-2017\/"]}]},{"@type":"WebSite","@id":"https:\/\/eva-vautier.com\/en\/#website","url":"https:\/\/eva-vautier.com\/en\/","name":"Galerie Eva Vautier","description":"Galerie d&#039;art contemporain","publisher":{"@id":"https:\/\/eva-vautier.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eva-vautier.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eva-vautier.com\/en\/#organization","name":"Galerie Eva Vautier","url":"https:\/\/eva-vautier.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eva-vautier.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/eva-vautier.com\/wp-content\/uploads\/2018\/09\/logo-galerie-illustrator-04-1.png","contentUrl":"http:\/\/eva-vautier.com\/wp-content\/uploads\/2018\/09\/logo-galerie-illustrator-04-1.png","width":200,"height":24,"caption":"Galerie Eva Vautier"},"image":{"@id":"https:\/\/eva-vautier.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/evavautier\/","https:\/\/x.com\/EvaVautier","https:\/\/www.instagram.com\/galerieevavautier\/"]},{"@type":"Person","@id":"https:\/\/eva-vautier.com\/en\/#\/schema\/person\/84de9580a67b26ee729034fb0254ead4","name":"eva Vautier","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eva-vautier.com\/wp-content\/litespeed\/avatar\/dd984889775f6320e22f927e54fb9523.jpg?ver=1788357180","url":"https:\/\/eva-vautier.com\/wp-content\/litespeed\/avatar\/dd984889775f6320e22f927e54fb9523.jpg?ver=1788357180","contentUrl":"https:\/\/eva-vautier.com\/wp-content\/litespeed\/avatar\/dd984889775f6320e22f927e54fb9523.jpg?ver=1788357180","caption":"eva Vautier"}}]}},"_links":{"self":[{"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/posts\/27375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/comments?post=27375"}],"version-history":[{"count":0,"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/posts\/27375\/revisions"}],"wp:attachment":[{"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/media?parent=27375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/categories?post=27375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/tags?post=27375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}