{"id":81111,"date":"2016-03-13T16:44:59","date_gmt":"2016-03-13T17:44:59","guid":{"rendered":"https:\/\/2023.eva-vautier.com\/portfolio-item\/carte-blanche-ben-vautier\/"},"modified":"2023-05-23T14:51:38","modified_gmt":"2023-05-23T15:51:38","slug":"carte-blanche-ben-vautier","status":"publish","type":"portfolio","link":"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/","title":{"rendered":"&#8220;Carte blanche&#8221; Ben Vautier"},"content":{"rendered":"<div class=\"vc_row wpb_row section vc_row-fluid\">\n<div class=\" full_section_inner clearfix\">\n<div class=\"vc_col-sm-12 wpb_column vc_column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element vc_custom_1456756951551\">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center;\">For its 17th exhibition, the Eva Vautier Gallery gives Ben Vautier carte blanche<\/p>\n<p style=\"text-align: center;\">from March to August 2016.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Ben becomes the curator and will in turn organize debates, performances and exhibitions of other artists.<\/p>\n<p style=\"text-align: center;\">The Gallery will be open at regular hours and by appointment.<\/p>\n<p style=\"text-align: center;\">The page below will inform you regularly of the programming:<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em><a href=\"http:\/\/eva-vautier.com\/carte-blanche-a-ben-vautier-a-la-galerie\/\">Ben Vautier&#8217;s Carte Blanche at the Gallery<\/a><\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":71032,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio-types":[2029,1765],"class_list":["post-81111","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-2016-en","portfolio-types-past"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Carte blanche&quot; Ben Vautier ~ Galerie Eva Vautier<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Carte blanche&quot; Ben Vautier ~ Galerie Eva Vautier\" \/>\n<meta property=\"og:description\" content=\"[\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/\" \/>\n<meta property=\"og:site_name\" content=\"Galerie Eva Vautier\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/evavautier\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-23T15:51:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eva-vautier.com\/wp-content\/uploads\/2016\/02\/carte-blanche-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EvaVautier\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/portfolio-item\\\/carte-blanche-ben-vautier\\\/\",\"url\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/portfolio-item\\\/carte-blanche-ben-vautier\\\/\",\"name\":\"\\\"Carte blanche\\\" Ben Vautier ~ Galerie Eva Vautier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/portfolio-item\\\/carte-blanche-ben-vautier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/portfolio-item\\\/carte-blanche-ben-vautier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eva-vautier.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/carte-blanche-1-scaled.jpg\",\"datePublished\":\"2016-03-13T17:44:59+00:00\",\"dateModified\":\"2023-05-23T15:51:38+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eva-vautier.com\\\/en\\\/portfolio-item\\\/carte-blanche-ben-vautier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/portfolio-item\\\/carte-blanche-ben-vautier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eva-vautier.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/carte-blanche-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/eva-vautier.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/carte-blanche-1-scaled.jpg\",\"width\":2560,\"height\":1548},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/\",\"name\":\"Galerie Eva Vautier\",\"description\":\"Galerie d&#039;art contemporain\",\"publisher\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#organization\",\"name\":\"Galerie Eva Vautier\",\"url\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/eva-vautier.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/logo-galerie-illustrator-04-1.png\",\"contentUrl\":\"http:\\\/\\\/eva-vautier.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/logo-galerie-illustrator-04-1.png\",\"width\":200,\"height\":24,\"caption\":\"Galerie Eva Vautier\"},\"image\":{\"@id\":\"https:\\\/\\\/eva-vautier.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/evavautier\\\/\",\"https:\\\/\\\/x.com\\\/EvaVautier\",\"https:\\\/\\\/www.instagram.com\\\/galerieevavautier\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Carte blanche\" Ben Vautier ~ Galerie Eva Vautier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/","og_locale":"en_US","og_type":"article","og_title":"\"Carte blanche\" Ben Vautier ~ Galerie Eva Vautier","og_description":"[\u2026]","og_url":"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/","og_site_name":"Galerie Eva Vautier","article_publisher":"https:\/\/www.facebook.com\/evavautier\/","article_modified_time":"2023-05-23T15:51:38+00:00","og_image":[{"width":2560,"height":1548,"url":"https:\/\/eva-vautier.com\/wp-content\/uploads\/2016\/02\/carte-blanche-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@EvaVautier","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/","url":"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/","name":"\"Carte blanche\" Ben Vautier ~ Galerie Eva Vautier","isPartOf":{"@id":"https:\/\/eva-vautier.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/#primaryimage"},"image":{"@id":"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/#primaryimage"},"thumbnailUrl":"https:\/\/eva-vautier.com\/wp-content\/uploads\/2016\/02\/carte-blanche-1-scaled.jpg","datePublished":"2016-03-13T17:44:59+00:00","dateModified":"2023-05-23T15:51:38+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eva-vautier.com\/en\/portfolio-item\/carte-blanche-ben-vautier\/#primaryimage","url":"https:\/\/eva-vautier.com\/wp-content\/uploads\/2016\/02\/carte-blanche-1-scaled.jpg","contentUrl":"https:\/\/eva-vautier.com\/wp-content\/uploads\/2016\/02\/carte-blanche-1-scaled.jpg","width":2560,"height":1548},{"@type":"WebSite","@id":"https:\/\/eva-vautier.com\/en\/#website","url":"https:\/\/eva-vautier.com\/en\/","name":"Galerie Eva Vautier","description":"Galerie d&#039;art contemporain","publisher":{"@id":"https:\/\/eva-vautier.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eva-vautier.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eva-vautier.com\/en\/#organization","name":"Galerie Eva Vautier","url":"https:\/\/eva-vautier.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eva-vautier.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/eva-vautier.com\/wp-content\/uploads\/2018\/09\/logo-galerie-illustrator-04-1.png","contentUrl":"http:\/\/eva-vautier.com\/wp-content\/uploads\/2018\/09\/logo-galerie-illustrator-04-1.png","width":200,"height":24,"caption":"Galerie Eva Vautier"},"image":{"@id":"https:\/\/eva-vautier.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/evavautier\/","https:\/\/x.com\/EvaVautier","https:\/\/www.instagram.com\/galerieevavautier\/"]}]}},"_links":{"self":[{"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/portfolio\/81111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/comments?post=81111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/media\/71032"}],"wp:attachment":[{"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/media?parent=81111"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/eva-vautier.com\/en\/wp-json\/wp\/v2\/portfolio-types?post=81111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}